{"id":27008,"date":"2022-01-20T15:35:08","date_gmt":"2022-01-20T14:35:08","guid":{"rendered":"https:\/\/apicstaging.wpengine.com\/?post_type=landing_pages&#038;p=27008"},"modified":"2024-08-20T15:00:24","modified_gmt":"2024-08-20T14:00:24","slug":"kostenloses-pdf-fb-einkaufsleitfaden-fuer-restaurant-manager","status":"publish","type":"landing_pages","link":"https:\/\/get.apicbase.com\/de\/kostenloses-pdf-fb-einkaufsleitfaden-fuer-restaurant-manager\/","title":{"rendered":"[Kostenloses PDF] F&#038;B-Einkaufsleitfaden f\u00fcr Restaurant-Manager"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"27008\" class=\"elementor elementor-27008 elementor-26697\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"landing_pages\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-70ec664f elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"70ec664f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5489a5e2 exad-glass-effect-no exad-sticky-section-no\" data-id=\"5489a5e2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f080138 elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit ob-harakiri-inherit exad-sticky-section-no exad-glass-effect-no ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"6f080138\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">[Kostenloses PDF] F&amp;B-Einkaufsleitfaden F\u00fcr Restaurants Mit Mehreren Betrieben<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-155996b exad-sticky-section-no exad-glass-effect-no ob-has-background-overlay elementor-widget elementor-widget-menu-anchor\" data-id=\"155996b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Header\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6afc8fcb ob-harakiri-inherit exad-sticky-section-no exad-glass-effect-no ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"6afc8fcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">In diesem Leitfaden f\u00fcr die Gastronomie finden Sie bew\u00e4hrte Taktiken und Richtlinien, die Restaurantmanagern helfen, bessere Kaufentscheidungen bei der Bestellung von Speisen und Getr\u00e4nken zu treffen. <\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ca19d2d exad-sticky-section-no exad-glass-effect-no ob-has-background-overlay elementor-widget elementor-widget-spacer\" data-id=\"7ca19d2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_spacerat_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19715e6d hubspot-contact-form exad-sticky-section-no exad-glass-effect-no ob-has-background-overlay elementor-widget elementor-widget-html\" data-id=\"19715e6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"html.default\">\n\t\t\t\t\t<!--[if lte IE 8]>\r\n<script charset=\"utf-8\" type=\"text\/javascript\" src=\"\/\/js.hsforms.net\/forms\/v2-legacy.js\"><\/script>\r\n<![endif]-->\r\n<script charset=\"utf-8\" type=\"text\/javascript\" src=\"\/\/js.hsforms.net\/forms\/v2.js\"><\/script>\r\n<script>\r\n  hbspt.forms.create({\r\n\tregion: \"na1\",\r\n\tportalId: \"5867239\",\r\n\tformId: \"a5e67663-9eb7-4d53-87f7-9b9245dd90b6\"\r\n});\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-29df2d3 exad-glass-effect-no exad-sticky-section-no\" data-id=\"29df2d3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c61d32c elementor-widget-mobile__width-inherit exad-sticky-section-no exad-glass-effect-no ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"7c61d32c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"442\" height=\"604\" src=\"https:\/\/get.apicbase.com\/wp-content\/uploads\/2022\/01\/fb-en.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-26702\" alt=\"Guide F&amp;B purchasing in restaurants\" srcset=\"https:\/\/get.apicbase.com\/wp-content\/uploads\/2022\/01\/fb-en.png 442w, https:\/\/get.apicbase.com\/wp-content\/uploads\/2022\/01\/fb-en-220x300.png 220w\" sizes=\"auto, (max-width: 442px) 100vw, 442px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-10be5eac elementor-section-full_width elementor-reverse-tablet elementor-reverse-mobile elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"10be5eac\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2bcf6a63 exad-glass-effect-no exad-sticky-section-no\" data-id=\"2bcf6a63\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ce6cbf4 ob-harakiri-inherit exad-sticky-section-no exad-glass-effect-no ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"3ce6cbf4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Laden Sie diesen Leitfaden herunter, um mehr zu erfahren:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29f8173 elementor-icon-list--layout-traditional elementor-list-item-link-full_width exad-sticky-section-no exad-glass-effect-no ob-has-background-overlay elementor-widget elementor-widget-icon-list\" data-id=\"29f8173\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"10\" viewBox=\"0 0 10 10\" fill=\"none\"><g clip-path=\"url(#clip0_5525_12844)\"><path d=\"M5 10C7.76142 10 10 7.76142 10 5C10 2.23858 7.76142 0 5 0C2.23858 0 0 2.23858 0 5C0 7.76142 2.23858 10 5 10Z\" fill=\"#FCC11A\"><\/path><\/g><defs><clipPath id=\"clip0_5525_12844\"><rect width=\"10\" height=\"10\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Warum robuste Beschaffungsprozesse wichtig sind<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"10\" viewBox=\"0 0 10 10\" fill=\"none\"><g clip-path=\"url(#clip0_5525_12844)\"><path d=\"M5 10C7.76142 10 10 7.76142 10 5C10 2.23858 7.76142 0 5 0C2.23858 0 0 2.23858 0 5C0 7.76142 2.23858 10 5 10Z\" fill=\"#FCC11A\"><\/path><\/g><defs><clipPath id=\"clip0_5525_12844\"><rect width=\"10\" height=\"10\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Wie man Die 6 Schritte des Beschaffungsprozesses in der Gastronomie verbessert<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"10\" viewBox=\"0 0 10 10\" fill=\"none\"><g clip-path=\"url(#clip0_5525_12844)\"><path d=\"M5 10C7.76142 10 10 7.76142 10 5C10 2.23858 7.76142 0 5 0C2.23858 0 0 2.23858 0 5C0 7.76142 2.23858 10 5 10Z\" fill=\"#FCC11A\"><\/path><\/g><defs><clipPath id=\"clip0_5525_12844\"><rect width=\"10\" height=\"10\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Entwurf von SOPs &amp; Richtlinien<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"10\" viewBox=\"0 0 10 10\" fill=\"none\"><g clip-path=\"url(#clip0_5525_12844)\"><path d=\"M5 10C7.76142 10 10 7.76142 10 5C10 2.23858 7.76142 0 5 0C2.23858 0 0 2.23858 0 5C0 7.76142 2.23858 10 5 10Z\" fill=\"#FCC11A\"><\/path><\/g><defs><clipPath id=\"clip0_5525_12844\"><rect width=\"10\" height=\"10\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Nachfrage als Ausl\u00f6ser, der den Prozess aktiviert<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"10\" viewBox=\"0 0 10 10\" fill=\"none\"><g clip-path=\"url(#clip0_5525_12844)\"><path d=\"M5 10C7.76142 10 10 7.76142 10 5C10 2.23858 7.76142 0 5 0C2.23858 0 0 2.23858 0 5C0 7.76142 2.23858 10 5 10Z\" fill=\"#FCC11A\"><\/path><\/g><defs><clipPath id=\"clip0_5525_12844\"><rect width=\"10\" height=\"10\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Welche Anbieter ausgew\u00e4hlt werden sollen (und wie sie ausgew\u00e4hlt werden)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"10\" viewBox=\"0 0 10 10\" fill=\"none\"><g clip-path=\"url(#clip0_5525_12844)\"><path d=\"M5 10C7.76142 10 10 7.76142 10 5C10 2.23858 7.76142 0 5 0C2.23858 0 0 2.23858 0 5C0 7.76142 2.23858 10 5 10Z\" fill=\"#FCC11A\"><\/path><\/g><defs><clipPath id=\"clip0_5525_12844\"><rect width=\"10\" height=\"10\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Wie Sie Bestellungen von Speisen und Getr\u00e4nken vorbereiten und aufgeben<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"10\" viewBox=\"0 0 10 10\" fill=\"none\"><g clip-path=\"url(#clip0_5525_12844)\"><path d=\"M5 10C7.76142 10 10 7.76142 10 5C10 2.23858 7.76142 0 5 0C2.23858 0 0 2.23858 0 5C0 7.76142 2.23858 10 5 10Z\" fill=\"#FCC11A\"><\/path><\/g><defs><clipPath id=\"clip0_5525_12844\"><rect width=\"10\" height=\"10\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Annahme, Kontrolle und Lagerung von Waren<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"10\" viewBox=\"0 0 10 10\" fill=\"none\"><g clip-path=\"url(#clip0_5525_12844)\"><path d=\"M5 10C7.76142 10 10 7.76142 10 5C10 2.23858 7.76142 0 5 0C2.23858 0 0 2.23858 0 5C0 7.76142 2.23858 10 5 10Z\" fill=\"#FCC11A\"><\/path><\/g><defs><clipPath id=\"clip0_5525_12844\"><rect width=\"10\" height=\"10\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00dcberpr\u00fcfen von Rechnungen und Zahlungen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"10\" viewBox=\"0 0 10 10\" fill=\"none\"><g clip-path=\"url(#clip0_5525_12844)\"><path d=\"M5 10C7.76142 10 10 7.76142 10 5C10 2.23858 7.76142 0 5 0C2.23858 0 0 2.23858 0 5C0 7.76142 2.23858 10 5 10Z\" fill=\"#FCC11A\"><\/path><\/g><defs><clipPath id=\"clip0_5525_12844\"><rect width=\"10\" height=\"10\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Wie eine simple Software einen gro\u00dfen Beitrag zur Kontrolle \u00fcber Bestellungen (und Lebensmittelkosten) in der Gastronomie leistet<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6d9593d9 exad-glass-effect-no exad-sticky-section-no\" data-id=\"6d9593d9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23f9d01d exad-sticky-section-no exad-glass-effect-no ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"23f9d01d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/get.apicbase.com\/wp-content\/uploads\/2021\/06\/1021313_Infographic_WithoutLogo_040121-768x576-1.png\" class=\"attachment-large size-large wp-image-22950\" alt=\"restaurant purchasing F&amp;B purchasing cycle\" srcset=\"https:\/\/get.apicbase.com\/wp-content\/uploads\/2021\/06\/1021313_Infographic_WithoutLogo_040121-768x576-1.png 768w, https:\/\/get.apicbase.com\/wp-content\/uploads\/2021\/06\/1021313_Infographic_WithoutLogo_040121-768x576-1-300x225.png 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-7db0a626 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"7db0a626\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e09543f exad-glass-effect-no exad-sticky-section-no\" data-id=\"4e09543f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-6bcada9c elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"6bcada9c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2f69e74e exad-glass-effect-no exad-sticky-section-no\" data-id=\"2f69e74e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fea8419 ob-harakiri-inherit exad-sticky-section-no exad-glass-effect-no ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"1fea8419\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ihr Ziel ist es, optimale Lagerbest\u00e4nde aufrechtzuerhalten, ohne zu viel auszugeben oder zu verschwenden.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-38a9be55 exad-glass-effect-no exad-sticky-section-no\" data-id=\"38a9be55\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1917dd ob-harakiri-inherit exad-sticky-section-no exad-glass-effect-no ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"a1917dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_postman_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>F&amp;B-Einkaufsfehler &amp; schlechte Bestandsverwaltung vor allem Fehler in der Beschaffung der Speisen und Getr\u00e4nke\u00a0der Hauptgrund daf\u00fcr sind, dass die Betreiber Schwierigkeiten haben, ihre Lebensmittelkosten unter Kontrolle zu bringen.<\/p>\n<p>Und selbst wenn Sie bei Beschaffungs- und Lieferantenverhandlungen ein Naturtalent sein m\u00f6gen, h\u00e4ufen sich diese Fehler trotzdem, wenn Sie Ihren Prozess nicht von Anfang bis Ende optimieren. Und diese Fehler summieren sich. Vor allem, wenn Sie sich um die Beschaffung f\u00fcr einen Betrieb mit mehreren Standorten k\u00fcmmern.<\/p>\n<p>Die Beschaffung in der Gastronomie\u00a0ist eine bewusste, zielgerichtete und sorgf\u00e4ltig geplante T\u00e4tigkeit, die sich mit der Suche, Auswahl, dem Kauf, der Annahme, der Lagerung, der Verwendung und der Kontrolle der f\u00fcr das Unternehmen entscheidenden Waren befasst. Ziel ist es, optimale Lagerbest\u00e4nde aufrechtzuerhalten, ohne zu viel auszugeben oder zu verschwenden.<\/p>\n<p>Die Beschaffung von Lebensmitteln und Getr\u00e4nken ist ein Prozess, der Sie zu Ihrem Ziel f\u00fchrt. Dieses Ziel kann wie folgt zusammengefasst werden \u2014&gt;\u00a0ausreichend Vorrat, keine Verschwendung, Kontrolle der Lebensmittelkosten.\u00a0<\/p>\n<p>Die Leitlinien in diesem herunterladbaren pdf-Dokument richten sich an Restaurantleiter, F&amp;B-Manager und Betriebsleiter in einem wachsenden Gastronomiebetrieb mit mehreren Einheiten, die sich darauf konzentrieren wollen:<\/p>\n<ul>\n<li>Dem richtigen Produkt<\/li>\n<li>Mit der richtigen Qualit\u00e4t<\/li>\n<li>Zum richtigen Preis<\/li>\n<li>Zum richtigen Zeitpunkt<\/li>\n<li>Von der richtigen Quelle<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-45f9d6b pre-footer-cta elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"45f9d6b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eb374b8 exad-glass-effect-no exad-sticky-section-no\" data-id=\"eb374b8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f87c16 ob-harakiri-inherit exad-sticky-section-no exad-glass-effect-no ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"1f87c16\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-xl\"><span style=\"font-weight: normal\">Niemals Zur Neige Gehen, Nicht Verschwenden, Hohe Lebensmittelkosten Eind\u00e4mmen<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdfe341 elementor-align-center exad-sticky-section-no exad-glass-effect-no ob-has-background-overlay elementor-widget elementor-widget-button\" data-id=\"fdfe341\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_butterbutton_use_it&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"#Header\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt Herunterladen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"content-type":""},"landing_page_type":[],"class_list":["post-27008","landing_pages","type-landing_pages","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>F&amp;B-Einkaufsleitfaden f\u00fcr Restaurant-Manager - Kostenloses PDF<\/title>\n<meta name=\"description\" content=\"Der F&amp;B-Einkauf in Restaurants ist ein komplexer Prozess. In diesem Leitfaden finden Sie Richtlinien f\u00fcr fehlerfreie Lieferantenbestellungen und zur Eind\u00e4mmung hoher CoGS.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/get.apicbase.com\/de\/kostenloses-pdf-fb-einkaufsleitfaden-fuer-restaurant-manager\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Kostenloses PDF] F&amp;B-Einkaufsleitfaden f\u00fcr Restaurant-Manager\" \/>\n<meta property=\"og:description\" content=\"Der F&amp;B-Einkauf in Restaurants ist ein komplexer Prozess. In diesem Leitfaden finden Sie Richtlinien f\u00fcr fehlerfreie Lieferantenbestellungen und zur Eind\u00e4mmung hoher CoGS.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/get.apicbase.com\/de\/kostenloses-pdf-fb-einkaufsleitfaden-fuer-restaurant-manager\/\" \/>\n<meta property=\"og:site_name\" content=\"Apicbase\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/apicbase\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-20T14:00:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/get.apicbase.com\/wp-content\/uploads\/2022\/01\/fb-en.png\" \/>\n\t<meta property=\"og:image:width\" content=\"442\" \/>\n\t<meta property=\"og:image:height\" content=\"604\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@apicbase\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/get.apicbase.com\/fb-purchasing-guide-restaurant\/\",\"url\":\"https:\/\/get.apicbase.com\/de\/kostenloses-pdf-fb-einkaufsleitfaden-fuer-restaurant-manager\/\",\"name\":\"F&B-Einkaufsleitfaden f\u00fcr Restaurant-Manager - Kostenloses PDF\",\"isPartOf\":{\"@id\":\"https:\/\/get.apicbase.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/get.apicbase.com\/de\/kostenloses-pdf-fb-einkaufsleitfaden-fuer-restaurant-manager\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/get.apicbase.com\/de\/kostenloses-pdf-fb-einkaufsleitfaden-fuer-restaurant-manager\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/get.apicbase.com\/wp-content\/uploads\/2022\/01\/fb-en.png\",\"datePublished\":\"2022-01-20T14:35:08+00:00\",\"dateModified\":\"2024-08-20T14:00:24+00:00\",\"description\":\"Der F&B-Einkauf in Restaurants ist ein komplexer Prozess. In diesem Leitfaden finden Sie Richtlinien f\u00fcr fehlerfreie Lieferantenbestellungen und zur Eind\u00e4mmung hoher CoGS.\",\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/get.apicbase.com\/de\/kostenloses-pdf-fb-einkaufsleitfaden-fuer-restaurant-manager\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/get.apicbase.com\/de\/kostenloses-pdf-fb-einkaufsleitfaden-fuer-restaurant-manager\/#primaryimage\",\"url\":\"https:\/\/get.apicbase.com\/wp-content\/uploads\/2022\/01\/fb-en.png\",\"contentUrl\":\"https:\/\/get.apicbase.com\/wp-content\/uploads\/2022\/01\/fb-en.png\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/get.apicbase.com\/#website\",\"url\":\"https:\/\/get.apicbase.com\/\",\"name\":\"Apicbase\",\"description\":\"#1 Restaurant Management Software\",\"publisher\":{\"@id\":\"https:\/\/get.apicbase.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/get.apicbase.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/get.apicbase.com\/#organization\",\"name\":\"Apicbase\",\"url\":\"https:\/\/get.apicbase.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/get.apicbase.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/get.apicbase.com\/wp-content\/uploads\/2025\/08\/apicbase-logo-black.svg\",\"contentUrl\":\"https:\/\/get.apicbase.com\/wp-content\/uploads\/2025\/08\/apicbase-logo-black.svg\",\"caption\":\"Apicbase\"},\"image\":{\"@id\":\"https:\/\/get.apicbase.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/apicbase\/\",\"https:\/\/x.com\/apicbase\",\"https:\/\/www.instagram.com\/apicbase\/\",\"https:\/\/www.linkedin.com\/company-beta\/5036984\/\",\"https:\/\/www.pinterest.com\/apicbase\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"F&B-Einkaufsleitfaden f\u00fcr Restaurant-Manager - Kostenloses PDF","description":"Der F&B-Einkauf in Restaurants ist ein komplexer Prozess. In diesem Leitfaden finden Sie Richtlinien f\u00fcr fehlerfreie Lieferantenbestellungen und zur Eind\u00e4mmung hoher CoGS.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/get.apicbase.com\/de\/kostenloses-pdf-fb-einkaufsleitfaden-fuer-restaurant-manager\/","og_locale":"de_DE","og_type":"article","og_title":"[Kostenloses PDF] F&B-Einkaufsleitfaden f\u00fcr Restaurant-Manager","og_description":"Der F&B-Einkauf in Restaurants ist ein komplexer Prozess. In diesem Leitfaden finden Sie Richtlinien f\u00fcr fehlerfreie Lieferantenbestellungen und zur Eind\u00e4mmung hoher CoGS.","og_url":"https:\/\/get.apicbase.com\/de\/kostenloses-pdf-fb-einkaufsleitfaden-fuer-restaurant-manager\/","og_site_name":"Apicbase","article_publisher":"https:\/\/www.facebook.com\/apicbase\/","article_modified_time":"2024-08-20T14:00:24+00:00","og_image":[{"width":442,"height":604,"url":"https:\/\/get.apicbase.com\/wp-content\/uploads\/2022\/01\/fb-en.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@apicbase","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/get.apicbase.com\/fb-purchasing-guide-restaurant\/","url":"https:\/\/get.apicbase.com\/de\/kostenloses-pdf-fb-einkaufsleitfaden-fuer-restaurant-manager\/","name":"F&B-Einkaufsleitfaden f\u00fcr Restaurant-Manager - Kostenloses PDF","isPartOf":{"@id":"https:\/\/get.apicbase.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/get.apicbase.com\/de\/kostenloses-pdf-fb-einkaufsleitfaden-fuer-restaurant-manager\/#primaryimage"},"image":{"@id":"https:\/\/get.apicbase.com\/de\/kostenloses-pdf-fb-einkaufsleitfaden-fuer-restaurant-manager\/#primaryimage"},"thumbnailUrl":"https:\/\/get.apicbase.com\/wp-content\/uploads\/2022\/01\/fb-en.png","datePublished":"2022-01-20T14:35:08+00:00","dateModified":"2024-08-20T14:00:24+00:00","description":"Der F&B-Einkauf in Restaurants ist ein komplexer Prozess. In diesem Leitfaden finden Sie Richtlinien f\u00fcr fehlerfreie Lieferantenbestellungen und zur Eind\u00e4mmung hoher CoGS.","inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/get.apicbase.com\/de\/kostenloses-pdf-fb-einkaufsleitfaden-fuer-restaurant-manager\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/get.apicbase.com\/de\/kostenloses-pdf-fb-einkaufsleitfaden-fuer-restaurant-manager\/#primaryimage","url":"https:\/\/get.apicbase.com\/wp-content\/uploads\/2022\/01\/fb-en.png","contentUrl":"https:\/\/get.apicbase.com\/wp-content\/uploads\/2022\/01\/fb-en.png"},{"@type":"WebSite","@id":"https:\/\/get.apicbase.com\/#website","url":"https:\/\/get.apicbase.com\/","name":"Apicbase","description":"#1 Restaurant Management Software","publisher":{"@id":"https:\/\/get.apicbase.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/get.apicbase.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/get.apicbase.com\/#organization","name":"Apicbase","url":"https:\/\/get.apicbase.com\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/get.apicbase.com\/#\/schema\/logo\/image\/","url":"https:\/\/get.apicbase.com\/wp-content\/uploads\/2025\/08\/apicbase-logo-black.svg","contentUrl":"https:\/\/get.apicbase.com\/wp-content\/uploads\/2025\/08\/apicbase-logo-black.svg","caption":"Apicbase"},"image":{"@id":"https:\/\/get.apicbase.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/apicbase\/","https:\/\/x.com\/apicbase","https:\/\/www.instagram.com\/apicbase\/","https:\/\/www.linkedin.com\/company-beta\/5036984\/","https:\/\/www.pinterest.com\/apicbase\/"]}]}},"_links":{"self":[{"href":"https:\/\/get.apicbase.com\/de\/wp-json\/wp\/v2\/landing_pages\/27008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/get.apicbase.com\/de\/wp-json\/wp\/v2\/landing_pages"}],"about":[{"href":"https:\/\/get.apicbase.com\/de\/wp-json\/wp\/v2\/types\/landing_pages"}],"version-history":[{"count":0,"href":"https:\/\/get.apicbase.com\/de\/wp-json\/wp\/v2\/landing_pages\/27008\/revisions"}],"wp:attachment":[{"href":"https:\/\/get.apicbase.com\/de\/wp-json\/wp\/v2\/media?parent=27008"}],"wp:term":[{"taxonomy":"landing_page_type","embeddable":true,"href":"https:\/\/get.apicbase.com\/de\/wp-json\/wp\/v2\/landing_page_type?post=27008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}