{"id":361,"count":3,"description":"","link":"https:\/\/get.apicbase.com\/fr\/category\/tendance\/","name":"Tendances","slug":"tendance","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tendances Archives - Apicbase<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez les derni\u00e8res tendances culinaires avec Apicbase. Explorez notre cat\u00e9gorie Tendances d\u00e8s maintenant.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/get.apicbase.com\/fr\/category\/tendance\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tendances Archives\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez les derni\u00e8res tendances culinaires avec Apicbase. Explorez notre cat\u00e9gorie Tendances d\u00e8s maintenant.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/get.apicbase.com\/fr\/category\/tendance\/\" \/>\n<meta property=\"og:site_name\" content=\"Apicbase\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@apicbase\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/get.apicbase.com\/fr\/category\/tendance\/\",\"url\":\"https:\/\/get.apicbase.com\/fr\/category\/tendance\/\",\"name\":\"Tendances Archives - Apicbase\",\"isPartOf\":{\"@id\":\"https:\/\/get.apicbase.com\/#website\"},\"description\":\"D\u00e9couvrez les derni\u00e8res tendances culinaires avec Apicbase. Explorez notre cat\u00e9gorie Tendances d\u00e8s maintenant.\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/get.apicbase.com\/#website\",\"url\":\"https:\/\/get.apicbase.com\/\",\"name\":\"Apicbase\",\"description\":\"#1 Restaurant Management Software\",\"publisher\":{\"@id\":\"https:\/\/get.apicbase.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/get.apicbase.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/get.apicbase.com\/#organization\",\"name\":\"Apicbase\",\"url\":\"https:\/\/get.apicbase.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/get.apicbase.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/get.apicbase.com\/wp-content\/uploads\/2025\/08\/apicbase-logo-black.svg\",\"contentUrl\":\"https:\/\/get.apicbase.com\/wp-content\/uploads\/2025\/08\/apicbase-logo-black.svg\",\"width\":133,\"height\":35,\"caption\":\"Apicbase\"},\"image\":{\"@id\":\"https:\/\/get.apicbase.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/apicbase\/\",\"https:\/\/x.com\/apicbase\",\"https:\/\/www.instagram.com\/apicbase\/\",\"https:\/\/www.linkedin.com\/company-beta\/5036984\/\",\"https:\/\/www.pinterest.com\/apicbase\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tendances Archives - Apicbase","description":"D\u00e9couvrez les derni\u00e8res tendances culinaires avec Apicbase. Explorez notre cat\u00e9gorie Tendances d\u00e8s maintenant.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/get.apicbase.com\/fr\/category\/tendance\/","og_locale":"fr_FR","og_type":"article","og_title":"Tendances Archives","og_description":"D\u00e9couvrez les derni\u00e8res tendances culinaires avec Apicbase. Explorez notre cat\u00e9gorie Tendances d\u00e8s maintenant.","og_url":"https:\/\/get.apicbase.com\/fr\/category\/tendance\/","og_site_name":"Apicbase","twitter_card":"summary_large_image","twitter_site":"@apicbase","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/get.apicbase.com\/fr\/category\/tendance\/","url":"https:\/\/get.apicbase.com\/fr\/category\/tendance\/","name":"Tendances Archives - Apicbase","isPartOf":{"@id":"https:\/\/get.apicbase.com\/#website"},"description":"D\u00e9couvrez les derni\u00e8res tendances culinaires avec Apicbase. Explorez notre cat\u00e9gorie Tendances d\u00e8s maintenant.","inLanguage":"fr-FR"},{"@type":"WebSite","@id":"https:\/\/get.apicbase.com\/#website","url":"https:\/\/get.apicbase.com\/","name":"Apicbase","description":"#1 Restaurant Management Software","publisher":{"@id":"https:\/\/get.apicbase.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/get.apicbase.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/get.apicbase.com\/#organization","name":"Apicbase","url":"https:\/\/get.apicbase.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/get.apicbase.com\/#\/schema\/logo\/image\/","url":"https:\/\/get.apicbase.com\/wp-content\/uploads\/2025\/08\/apicbase-logo-black.svg","contentUrl":"https:\/\/get.apicbase.com\/wp-content\/uploads\/2025\/08\/apicbase-logo-black.svg","width":133,"height":35,"caption":"Apicbase"},"image":{"@id":"https:\/\/get.apicbase.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/apicbase\/","https:\/\/x.com\/apicbase","https:\/\/www.instagram.com\/apicbase\/","https:\/\/www.linkedin.com\/company-beta\/5036984\/","https:\/\/www.pinterest.com\/apicbase\/"]}]}},"_links":{"self":[{"href":"https:\/\/get.apicbase.com\/fr\/wp-json\/wp\/v2\/categories\/361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/get.apicbase.com\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/get.apicbase.com\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/get.apicbase.com\/fr\/wp-json\/wp\/v2\/posts?categories=361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}